{"id":85,"count":1,"description":"","link":"http:\/\/aquasapiens.fr\/aqua\/portfolio_category\/institutionnel\/","name":"Institutionnel","slug":"institutionnel","taxonomy":"portfolio_category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/aquasapiens.fr\/aqua\/wp-json\/wp\/v2\/portfolio_category\/85","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/aquasapiens.fr\/aqua\/wp-json\/wp\/v2\/portfolio_category"}],"about":[{"href":"http:\/\/aquasapiens.fr\/aqua\/wp-json\/wp\/v2\/taxonomies\/portfolio_category"}],"wp:post_type":[{"href":"http:\/\/aquasapiens.fr\/aqua\/wp-json\/wp\/v2\/avada_portfolio?portfolio_category=85"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}